{"id":2466,"date":"2025-07-10T02:32:11","date_gmt":"2025-07-10T06:32:11","guid":{"rendered":"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/?p=2466"},"modified":"2025-07-10T02:32:14","modified_gmt":"2025-07-10T06:32:14","slug":"el-blog-miercoles-09-de-julio-del-2025","status":"publish","type":"post","link":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/el-blog-miercoles-09-de-julio-del-2025\/","title":{"rendered":"El Blog: MI\u00c9RCOLES 09 DE JULIO del 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">PUBLICACI\u00d3N 6<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Baile<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante esta semana, los proyectos se prepararon para las presentaciones finales. Para esta presentaci\u00f3n, el baile trabaj\u00f3 en un baile secreto con Profe Mingee y Mentora Medaly. Las chicas llevaban faldas largas con colores brillantes y los chicos llevaban sombreros y pa\u00f1uelos. Para practicar, Profe Mingee mand\u00f3 que los estudiantes se formen en l\u00edneas y entonces en un c\u00edrculo. Ella cambi\u00f3 sus poses y les ense\u00f1\u00f3 el baile con la ayuda de T\u00faTubo para una visual. Ellos se enfocaron en las posiciones primero para mantener orden durante cada baile. En las im\u00e1genes podemos ver un baile tradicional de la pollera coloreada. Para ense\u00f1ar a los estudiantes, Profe Mingee trabaj\u00f3 con cada estudiante individualmente. Este baile ser\u00e1 brillante para mirar.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escritores: Gul, Jaideep, y Mallory<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2470\" data-id=\"2470\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8502-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8502-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8502-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2469\" data-id=\"2469\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8503-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8503-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8503-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2468\" data-id=\"2468\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8514-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8514-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8514-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2467\" data-id=\"2467\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8517-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8517-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8517-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2471\" data-id=\"2471\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8499-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8499-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8499-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Tuna&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Tuna es el proyecto musical de la academia espa\u00f1ola que contiene cantantes y m\u00fasicos que tocan varios instrumentos en canciones hermosas. El lunes, visitamos la Tuna durante su tiempo de pr\u00e1ctica y observamos lo que estaban haciendo. En el primer sal\u00f3n, algunos m\u00fasicos estaban tocando sus instrumentos como la guitarra, la flauta, el viol\u00edn, el clarinete, el teclado, y varios tipos de percusi\u00f3n. Afuera del sal\u00f3n, las cantantes estaban explicando y discutiendo la letra de una canci\u00f3n. Todo este trabajo es para las presentaciones finales de la academia, donde ellos van a cantar para las familias, los profes, los mentores, y los estudiantes. La Tuna tambi\u00e9n toca sus canciones en su presentaci\u00f3n semanal de su proyecto. Ya disfrutamos de canciones como \u201cMamma mia\u201d por ABBA (en espa\u00f1ol por supuesto) y \u201cDos oruguitas\u201d de la pel\u00edcula Encanto.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escritores: Danielle, Wyatt, y Catriona<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2474\" data-id=\"2474\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8563-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8563-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8563-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2476\" data-id=\"2476\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8559-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8559-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8559-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2475\" data-id=\"2475\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8564-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8564-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8564-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Telenovela<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este proyecto se enfoca en crear una trilog\u00eda dram\u00e1tica y c\u00f3mica en vivo que refleja las caracter\u00edsticas de una telenovela. Usan varios efectos de sonido, fondos, disfraces, y actores para contar una historia escrita por ellos mismos. El blog observ\u00f3 una continuaci\u00f3n del pr\u00f3ximo episodio y tuvo la oportunidad de mirar como ellos trabajan y practican.&nbsp; Para realizar la telenovela, los miembros se sientan en un c\u00edrculo alrededor de una proyecci\u00f3n de un documento con la Profe Wright y Mentor Preston. Este documento incluye las ideas, los fondos posibles, y las l\u00edneas del cuento. En el centro del c\u00edrculo, algunos actores presentan sus escenarios mientras el resto del grupo funciona como una audiencia. Pueden proveer sus consejos e ideas para desarrollar la historia.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brevemente, sin muchos detalles, la trama trata de un hombre, Juan Carlos, que est\u00e1 tratando de robar una taquer\u00eda \u2018real\u2019 de una familia rica. Pero, en su persecuci\u00f3n de la meta, Juan Carlos se enamor\u00f3 con la hija mayor, Marrrrrriiiiiiaaa (mah-RRRREE-juh), y perdi\u00f3 sus ganas de robar el lugar. Sin embargo, la familia no aprob\u00f3 la relaci\u00f3n y ellos tuvieron que separarse. En el segundo cap\u00edtulo, Marrrrrriiiiiiaaa (mah-RRRREE-juh) se convirti\u00f3 en una mujer poderosa e independiente. Ahora ella est\u00e1 lista para buscar a un novio en \u201cnovio r\u00e1pido&#8221;. Inesperadamente, el gemelo de Juan Carlos, Cuan Jarlos, apareci\u00f3 como uno de los candidatos. Ahora esperamos el ganador en el pr\u00f3ximo episodio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escritores: Sylvia y Nikoloz<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2478\" data-id=\"2478\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8530-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8530-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8530-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2479\" data-id=\"2479\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8527-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8527-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8527-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2480\" data-id=\"2480\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8526-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8526-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8526-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2477\" data-id=\"2477\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8531-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8531-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8531-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Radio<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La radio es uno de los proyectos ofrecidos en la academia y su meta es compartir los eventos actuales del mundo al resto de la academia. Este equipo trabaja en el tercer piso con Profe Garc\u00eda y Mentora Lara, y los chicos colaboran juntos. Adem\u00e1s, utilizan las computadoras mientras escriben apuntes sobre la mesa grande. Los estudiantes est\u00e1n ocupados investigando entre varias fuentes en sitios web como CNN Latinoam\u00e9rica, Wikipedia y ESPN. Despu\u00e9s de toda la investigaci\u00f3n, ellos preparan y presentan las noticias en el teatro cada viernes. Primero, empiezan con los eventos mundiales, algunas noticias son serias y otras m\u00e1s positivas. Despu\u00e9s, se incluyen las entrevistas de estudiantes durante la semana, los deportes, y los eventos hist\u00f3ricos. En la presentaci\u00f3n en la semana anterior, ellos compartieron superlativos como \u201cM\u00e1s chistoso\u201d, \u201cEl mejor estilo\u201d, y \u201cLa dormilona\u201d.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escritores: Aubrey, Marla, y Julia&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2483\" data-id=\"2483\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8536-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8536-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8536-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2482\" data-id=\"2482\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8537-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8537-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8537-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2481\" data-id=\"2481\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8551-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8551-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8551-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El Blog: \u00bfC\u00f3mo cu\u00e1ndo&#8230;?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el blog, nosotros tenemos la responsabilidad de escribir sobre los eventos de la academia para los padres y los estudiantes. Durante nuestro tiempo en el blog, nosotros aprendimos cu\u00e1les detalles y caracter\u00edsticas son importantes para mejorar una cuenta y cautivar a una audiencia. Pudimos combinar elementos graciosos con los recuerdos de la academia para compartir nuestra experiencia. Aprendimos m\u00e1s del uso de gram\u00e1tica en espa\u00f1ol y tambi\u00e9n sobre c\u00f3mo colaborar usando un idioma nuevo. Durante el blog, compartimos un ambiente \u00fanico donde podemos expresar nuestra creatividad juntos. No podemos olvidar los momentos c\u00f3micos los unos con los otros durante el proceso. Nos sentimos muy afortunados de tener a la Profe Quiroz y la Mentora Samantha para apoyarnos. Los momentos c\u00f3micos durante el proceso son inolvidables!\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escritores: El Blog \ud83d\ude42<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2484\" data-id=\"2484\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8656-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8656-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8656-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2485\" data-id=\"2485\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8657-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8657-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8657-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2486\" data-id=\"2486\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8658-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8658-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8658-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2487\" data-id=\"2487\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8659-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8659-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8659-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-2488\" data-id=\"2488\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8660-scaled.jpg\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8660-scaled.jpg 2560w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2025\/07\/IMG_8660-300x200.jpg 300w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>\u00a1Gracias por leer!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUBLICACI\u00d3N 6 Baile&nbsp; Durante esta semana, los proyectos se prepararon para las presentaciones finales. Para esta presentaci\u00f3n, el baile trabaj\u00f3 &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-2466","post","type-post","status-publish","format-standard","hentry","category-uncategorized","latest_post"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9TuOs-DM","_links":{"self":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/2466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/comments?post=2466"}],"version-history":[{"count":1,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/2466\/revisions"}],"predecessor-version":[{"id":2489,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/2466\/revisions\/2489"}],"wp:attachment":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/media?parent=2466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/categories?post=2466"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/tags?post=2466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}