{"id":2176,"date":"2024-07-09T23:28:48","date_gmt":"2024-07-10T03:28:48","guid":{"rendered":"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/?p=2176"},"modified":"2024-07-09T23:28:51","modified_gmt":"2024-07-10T03:28:51","slug":"el-periodico-de-la-academia-espanola-2024-julio-1-6","status":"publish","type":"post","link":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/el-periodico-de-la-academia-espanola-2024-julio-1-6\/","title":{"rendered":"El Peri\u00f3dico de la Academia Espa\u00f1ola 2024: Julio 1-6"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00a1Hola a todos! Como en cada publicaci\u00f3n, hoy nuestra sopa de letras no pod\u00eda faltar. Esta vez, la tem\u00e1tica son los dialectos del mundo hispanohablante. \u00a1A ver si encuentran todas!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El juego<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" src=\"blob:https:\/\/www.vagovernorsschool.com\/44cc497c-a39a-41d1-9765-8688f15ea767\">\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El D\u00eda a D\u00eda<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lunes, 1 de julio<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Empezamos la semana con un lunes regular. Hicimos nuestras actividades diarias con clases en la ma\u00f1ana; luego, la actividad cultural del D\u00eda de las Velitas con la Profesora Mingee; despu\u00e9s nuestra Telenovela: <em>El Tiempo Entre Costuras; <\/em>Tertulia Hablada con los mentores; trabajar en los proyectos y, finalmente, gozar de los deportes. Como ya ver\u00e1n, van a notar que este d\u00eda, sin duda, fue el m\u00e1s tranquillo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Actividad Cultural:<\/strong> En el D\u00eda de las Velitas, las familias colombianas inauguran la temporada navide\u00f1a. Por tradici\u00f3n, estos faroles son de fabricaci\u00f3n artesanal, con papel decorado. Se celebra los d\u00edas 7 y 8 diciembre. Nosotros los estudiantes creamos nuestras propias Velitas con palos de madera, pegamento y, lo m\u00e1s importante, nuestra imaginaci\u00f3n. Las velitas sirvieron como decoraciones para nuestros dormitorios. Despu\u00e9s de crear las Velitas, tuvimos la oportunidad de crear pulseras de letras en bloques. Estas pulseras intentaron reflejar nuestra personalidad o algo que sea muy importante en la vida.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-14.png\"><img loading=\"lazy\" decoding=\"async\" width=\"692\" height=\"622\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-14.png\" alt=\"\" class=\"wp-image-2180\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-14.png 692w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-14-300x270.png 300w\" sizes=\"auto, (max-width: 692px) 100vw, 692px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-18.png\"><img loading=\"lazy\" decoding=\"async\" width=\"692\" height=\"620\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-18.png\" alt=\"\" class=\"wp-image-2184\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-18.png 692w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-18-300x269.png 300w\" sizes=\"auto, (max-width: 692px) 100vw, 692px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Martes, 2 de julio<\/strong>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-19.png\"><img loading=\"lazy\" decoding=\"async\" width=\"671\" height=\"585\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-19.png\" alt=\"\" class=\"wp-image-2188\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-19.png 671w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-19-300x262.png 300w\" sizes=\"auto, (max-width: 671px) 100vw, 671px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-13.png\"><img loading=\"lazy\" decoding=\"async\" width=\"664\" height=\"583\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-13.png\" alt=\"\" class=\"wp-image-2179\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-13.png 664w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-13-300x263.png 300w\" sizes=\"auto, (max-width: 664px) 100vw, 664px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El Viaje a D.C.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s del desayuno, nosotros viajamos a Washington D.C. para la segunda excursi\u00f3n de la Academia Espa\u00f1ola al Instituto Cultural Mexicano del Washington D.C. Quiz\u00e1s ustedes se est\u00e1n preguntando, \u00bfqu\u00e9 es eso? Pues, el Instituto Cultural Mexicano es un centro de exhibici\u00f3n de arte que muestra la historia y cultura de M\u00e9xico que ha influido el trabajo de artistas mexicanos. Durante nuestro tiempo en este museo, tuvimos la oportunidad para explorar y aprender m\u00e1s sobre muchas piezas de arte mexicano. Espec\u00edficamente, nos encant\u00f3 ver la mezcla de aspectos modernos e ind\u00edgenas en el arte.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, nosotros visitamos La Cosecha, un mercado en D.C. con unas tiendas latinas en las que pudimos comprar recuerdos culturales y tambi\u00e9n comida de muchos restaurantes hispanohablantes diferentes. Como los trabajadores del mercado hablaban espa\u00f1ol, tuvimos la oportunidad de practicar nuestras habilidades de espa\u00f1ol.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vuelta a Lexington fue un poco larga porque uno de los colectivos se descompuso, pero pasamos un buen tiempo bueno charlando y jugando con nuestros amigos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mi\u00e9rcoles, 3 de julio<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bueno el mi\u00e9rcoles fue un d\u00eda lento lleno de fiaca. Comenzamos nuestro d\u00eda a las 11, algunas horas m\u00e1s tarde de lo usual, por haber tenido un d\u00eda tan loco el d\u00eda anterior.&nbsp; Aunque todos no estaban en el mismo colectivo, estuvimos muy contentos de saber que nuestros compa\u00f1eros, mentores, y profesores lograron llegar bien a sus dormitorios.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de desayunar, estuvimos listos para aprender los temas de las clases. Aunque el mi\u00e9rcoles fue un d\u00eda de descanso, nuestros maestros nos empujaron a aprovechar de los consejos disponibles al momento. Todav\u00eda estamos disfrutando nuestras clases.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seguimos con la tertulia hablada que fue un alivio para ambos maestros y estudiantes. Las tertulias habladas siempre son una diversi\u00f3n con nuestros mentores que siempre apoyan nuestras ideas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo tanto, tuvimos una noche libre y no sab\u00edamos qu\u00e9 hacer con el tiempo libre. Eventualmente, la Profesora Quiroz, una de las mejores, tuvo la idea de ver la pel\u00edcula Luca en italiano con subt\u00edtulos en espa\u00f1ol. Aprendimos que Luca vive en el mar cerca de las Cinco Tierra y que nunca ha salido a la superficie, hasta que conoci\u00f3 a un chico llamado Alberto. En la tierra los dos quer\u00edan una Vespa, un tipo de motocicleta, y con la ayuda de Giulia, una ni\u00f1a de la tierra, los tres compitieron y ganaron la copa Portorosso. Podemos agradecer los temas de amistad y diferencias, pero aprendimos que el espa\u00f1ol difiere del italiano y que todos hablamos con un ritmo diferente.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-3.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-3-1024x576.jpeg\" alt=\"\" class=\"wp-image-2186\" style=\"width:243px;height:auto\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-3-1024x576.jpeg 1024w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-3-300x169.jpeg 300w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-3-768x432.jpeg 768w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-3.jpeg 1123w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jueves, 4 de julio<\/strong>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-17.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"625\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-17-1024x625.png\" alt=\"\" class=\"wp-image-2183\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-17-1024x625.png 1024w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-17-300x183.png 300w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-17-768x468.png 768w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-17-750x458.png 750w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-17.png 1141w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mercado Internacional<\/strong>: \u00a1Feliz Dia de Independencia! En lugar de clases y una actividad cultural hoy, la Academia Espa\u00f1ola asisti\u00f3 al Mercado Internacional con los franceses y alemanes. Cada estudiante recibi\u00f3 15 boletas para comprar cualquier cosa en el Mercado y tuvo la opci\u00f3n para vender sus propias creaciones. Adem\u00e1s, tuvimos la oportunidad para competir en los juegos ol\u00edmpicos. Hab\u00eda muchos eventos: voleibol, correr con las piernas atadas a un amigo, saltar en una bolsa, lanzar una bolsa de frijoles, llenar cajas de agua con esponjas y hasta el \u201cHula Hula.\u201d&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-12.png\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"687\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-12.png\" alt=\"\" class=\"wp-image-2178\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-12.png 700w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-12-300x294.png 300w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-12-70x70.png 70w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-15.png\"><img loading=\"lazy\" decoding=\"async\" width=\"702\" height=\"687\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-15.png\" alt=\"\" class=\"wp-image-2181\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-15.png 702w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-15-300x294.png 300w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-15-70x70.png 70w\" sizes=\"auto, (max-width: 702px) 100vw, 702px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Telenovela<\/strong>: Despu\u00e9s, fuimos al teatro para finalizar un episodio de nuestra telenovela, <em>El Tiempo Entre Costuras<\/em>. Hoy tuvimos el doble de tiempo para mirarlo porque no tuvimos nuestra actividad de Tertulia. A causa de este tiempo adicional, mucho pas\u00f3. \u00a1Ignacio volvi\u00f3 y ahora \u00e9l trabaja para el Gobierno de Madrid! \u00a1Dejen fluir sus pensamientos!&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Viernes, 5 de julio<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Actividad Cultural:<\/strong> \u00bfUstedes recuerdan los alebrijes que nosotros hicimos la \u00faltima semana? Pues, despu\u00e9s de clases el viernes, para nuestra actividad cultural, nosotros tuvimos la oportunidad de expresar nuestra creatividad cuando finalizamos nuestros alebrijes. Cada estudiante pint\u00f3 su propia creaci\u00f3n \u00fanica con una variedad de dise\u00f1os y colores.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Presentaciones: <\/strong>Los grupos que presentaron el viernes fueron dise\u00f1o gr\u00e1fico, la tuna, y el baile. Toda esta semana, los estudiantes en estos grupos trabajaron incre\u00edblemente para entretener a la audiencia con sus presentaciones. Espec\u00edficamente, a nosotros nos encantaron la salsa que el grupo de baile hizo, el concierto maravilloso de la tuna, y, el mejor de todos, la presentaci\u00f3n espectacular del dise\u00f1o gr\u00e1fico con una secci\u00f3n emocionante nueva: \u00a1el chisme!\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Noche de Talentos: <\/strong>\u00bfLes gusta el programa de entretenimiento llamado \u201cLos Estados Unidos tienen Talentos?\u201d \u00a1Entonces, ustedes tendr\u00edan que ver los talentos ocultos de los estudiantes de la Academia Espa\u00f1ola! Esta noche, tuvimos un evento muy especial y divertido: La Noche de Talentos. La audiencia no pod\u00eda quitar sus ojos de las fant\u00e1sticas presentaciones y tuvimos la oportunidad de bailar, cantar, hacer sonidos de animales, agarrar uvas voladoras solo con la boca, \u00a1y m\u00e1s! La pr\u00f3xima semana, vamos a tener una noche de talentos internacional con las otras academias. Sin duda, \u00a1estamos muy emocionados!\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/IMG_4036-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/IMG_4036-scaled.jpeg\" alt=\"\" class=\"wp-image-2194\" style=\"width:520px;height:auto\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00e1bado, 6 de julio<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Actividad Cultural: <\/strong>Despu\u00e9s de clases el s\u00e1bado, como siempre, tuvimos nuestra actividad cultural. La Mentora Rheannon nos ense\u00f1\u00f3 sobre una tradici\u00f3n ecuatoriana que se llama el D\u00eda de los Difuntos. Con ra\u00edces en las comunidades ind\u00edgenas, el d\u00eda esta caracterizado por dos alimentos: Guaguas de Pan y la Colada Morada. El consumo de estos alimentos \u201creflejan una fusi\u00f3n de costumbres, sabores e historias.\u201d A trav\u00e9s de muchos siglos, el consumo de Guaguas de Pan y la Colada Morada se ha convertido en un sin\u00f3nimo de celebraci\u00f3n o reuni\u00f3n familiar en cementerios para recordar sus muertos. El s\u00e1bado, nosotros tuvimos la oportunidad de crear nuestros propias Guaguas de Pan, pero no hicimos la Colada Morada. Decoramos el Pan con confitura de una variedad de colores, y luego los comimos. \u00a1Aunque comiendo nuestras propias creaciones fue dif\u00edcil, estuvieron ricas!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las Segundas Presentaciones<\/strong>: Continuando las presentaciones de ayer, el segundo grupo de proyectos present\u00f3. Este grupo incluy\u00f3 a la Telenovela y la Radio. La Telenovela present\u00f3 primero con su episodio dos de <em>El Soltero. <\/em>Fue un episodio muy dram\u00e1tico y lleno de acci\u00f3n. \u00a1Todos quieren matar a todos! No tengan miedo, es solo para la telenovela. Sin exagerar, estamos muy emocionados por ver el \u00faltimo episodio. Despu\u00e9s, la Radio present\u00f3 con un formato nuevo. Adem\u00e1s de las secciones de la otra semana, ellos presentaron la informaci\u00f3n de deportes con bromas maravillosas. Los Mets no son el mejor equipo, pero Henry no est\u00e1 listo para esta conversaci\u00f3n.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/P2271105-2.jpg\"><img decoding=\"async\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/P2271105-2.jpg\" alt=\"\" class=\"wp-image-2196\"\/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Baile Internacional<\/strong>: En lugar de deportes el s\u00e1bado, nosotros asistimos al Baile Internacional entre las Academias de espa\u00f1ol, franc\u00e9s y alem\u00e1n. Durante el baile, todas las Academias socializaron con todos (lo mejor que pudieron) y mostraron sus movimientos. Adem\u00e1s, las Academias tuvieron la oportunidad de ense\u00f1ar sus propios bailes con las otras Academias. Aunque hac\u00eda mucho calor adentro del edificio, fue una noche llena de diversi\u00f3n. \u00a1Es evidente que a todo el mundo le encanta Gasolina!&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-16.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"601\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-16-1024x601.png\" alt=\"\" class=\"wp-image-2182\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-16-1024x601.png 1024w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-16-300x176.png 300w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-16-768x451.png 768w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/image-16.png 1188w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/20240706_193313-scaled.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" src=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/20240706_193313-1024x461.jpeg\" alt=\"\" class=\"wp-image-2197\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/20240706_193313-1024x461.jpeg 1024w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/20240706_193313-300x135.jpeg 300w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/20240706_193313-768x346.jpeg 768w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/20240706_193313-1536x692.jpeg 1536w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2024\/07\/20240706_193313-2048x922.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Noticias en el mundo hispanohablante<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El hurac\u00e1n Beryl<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer hurac\u00e1n atl\u00e1ntico del a\u00f1o, llamado Beryl, se est\u00e1 moviendo a trav\u00e9s del Caribe. Empez\u00f3 en las semanas pasadas, pero alcanz\u00f3 su nivel m\u00e1ximo el primero de julio con una categor\u00eda 5, y ahora ha bajado a una categor\u00eda 4. Varios pa\u00edses como Jamaica, Cuba, Honduras, Belice y M\u00e9xico que est\u00e1n en su trayectoria han sufrido da\u00f1os de tormentas e inundaciones, dejando al menos nueve fallecidos. La velocidad de su formaci\u00f3n y crecimiento est\u00e1 rompiendo r\u00e9cords, y esto est\u00e1 relacionado con el cambio clim\u00e1tico. Usualmente, huracanes empiezan en agoste a\u00f1o, la superficie del mar Atl\u00e1ntico est\u00e1 m\u00e1s caliente, lo que provoc\u00f3 el comienzo temprano y r\u00e1pido de Beryl. Desafortunadamente, esto indica que las tormentas comenzaran m\u00e1s temprano en a\u00f1os futuros.<img decoding=\"async\" src=\"blob:https:\/\/www.vagovernorsschool.com\/34d5186a-3ec4-452b-b3ec-f2d82ab0195a\">&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La independencia de Venezuela<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de los sonidos de las \u00e1guilas y fuegos artificiales en los Estados Unidos de Am\u00e9rica, celebramos el cumplea\u00f1os n\u00famero doscientos trece de Venezuela, y su independencia a pesar de olas de inestabilidad pol\u00edtica y militar. Para celebrar, es un buen tiempo para compartir 9 cosas \u00fanicas del pa\u00eds Venezuela.&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"1\">\n<li>Venezuela tiene la cascada ininterrumpida m\u00e1s alta del mundo.\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\">\n<li>El Catatumbo recibi\u00f3 un r\u00e9cord Guinness en 2013 por la \u201cmayor concentraci\u00f3n de rel\u00e1mpagos.\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"3\">\n<li>Es el pa\u00eds latinoamericano con m\u00e1s coronas de Miss Universo y Miss Mundo, y la \u00fanica naci\u00f3n de tener dos coronas consecutivas en Miss Universo.\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"4\">\n<li>Venezuela es parte de la zona m\u00e1s biodiversa del mundo: los Andes Tropicales.\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"5\">\n<li>Tiene la arepa m\u00e1s grande del mundo.\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"6\">\n<li>El deporte m\u00e1s popular es el beisbol, y en 2018 un total de 74 jugadores venezolanos estuvieron para el comienzo de la temporada.\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"7\">\n<li>Tiene el mayor goleador de las MLS.\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"8\">\n<li>La vacuna contra la lepra se invent\u00f3 en Venezuela.\u00a0<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"9\">\n<li>Tiene una reserva de 298.000 millones de barriles de petr\u00f3leo.\u00a0<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Inteligencia artificial en la m\u00fasica<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comentario de opini\u00f3n sobre el art\u00edculo &#8220;<a href=\"https:\/\/es.wired.com\/articulos\/inteligencia-artificial-abrira-una-nueva-era-para-la-musica-sera-buena\" target=\"_blank\" rel=\"noreferrer noopener\">La inteligencia artificial abrir\u00e1 una nueva era para la m\u00fasica, \u00bfser\u00e1 buena? | WIRED<\/a>&#8221;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" src=\"blob:https:\/\/www.vagovernorsschool.com\/8b4adae5-200e-4075-93b9-b27e7930a054\">Hoy en d\u00eda, un mundo llena de oportunidades nuevas por la inteligencia artificial espera a las generaciones del futuro. Un sitio de web publicado por Michael Sayman, un ingeniero de <em>software, <\/em>llamado <strong>AI Hits<\/strong> ha encontrado mucho \u00e9xito. Con la capacidad de imitar las voces de varios cantantes famosos, cualquier persona puede entrar algunos datos sobre la letra que quiere y tendr\u00e1 una nueva canci\u00f3n en segundos. Por ejemplo, UMG, la firma de disca que representa al rapero Drake, ha estado presionando compa\u00f1\u00edas grandes como Spotify para que se retiren canciones creadas por IA. Estas sienten que la pr\u00e1ctica parece ser algo \u201cmalvada y demoniaca\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, la inteligencia artificial puede ser una manera revolucionaria de comprender canciones en un idioma extranjero, para hablantes de diferentes lenguas que normalmente no pueden acceder a canciones internacionales. Sayman viene de una familia peruana, y por eso, est\u00e1 tratando de desarrollar el <em>software<\/em> para que sus usuarios puedan escuchar sus cantantes favoritos en su propio idioma. Por ejemplo, \u00e9l se tradujo su canci\u00f3n favorita de Rihanna en espa\u00f1ol sin sacrificar la harmon\u00eda de las letras o el ritmo. La m\u00fasica es una lengua universal, y afortunadamente, hay muchos avances a trav\u00e9s de inteligencia artificial que puede cambiar el disfrute de m\u00fasica para el mundo hispanohablante.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias por leernos y acompa\u00f1arnos en esta aventura. \u00a1Hasta la pr\u00f3xima!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Referencias:&nbsp;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/elpais.com\/tecnologia\/branded\/inteligencia-artificial\/2024-06-27\/la-ia-cambio-economico-y-social-para-espana.html\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La IA: cambio econ\u00f3mico y social para Espa\u00f1a | Inteligencia Artificial | EL PA\u00cdS (elpais.com)<\/strong><\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/elpais.com\/estilo-de-vida\/2024-06-29\/ganar-dinero-por-ver-videos-andar-o-leer-los-peligros-de-las-aplicaciones-que-monetizan-la-rutina.html\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Ganar dinero por ver v\u00eddeos, andar o leer: los peligros de las aplicaciones que monetizan la rutina | Estilo de vida | EL PA\u00cdS (elpais.com)<\/strong><\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/cnnespanol.cnn.com\/2024\/07\/02\/huracan-beryl-cambio-climatico-orix\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/cnnespanol.cnn.com\/2024\/07\/02\/huracan-beryl-cambio-climatico-orix\/<\/a>\u00a0\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/elpais.com\/mexico\/2024-07-07\/la-trayectoria-del-huracan-beryl-en-vivo.html\" target=\"_blank\" rel=\"noreferrer noopener\">elpais.com\/mexico\/2024-07-07\/la-trayectoria-del-huracan-beryl-en-vivo.html<\/a>\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/cnnespanol.cnn.com\/2024\/07\/05\/independencia-venezuela-origen-por-que-se-celebra-5-de-julio-orix\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/cnnespanol.cnn.com\/2024\/07\/05\/independencia-venezuela-origen-por-que-se-celebra-5-de-julio-orix\/<\/a>\u00a0\u00a0<\/li>\n\n\n\n<li><a href=\"https:\/\/www.turismo.gob.ec\/dia-de-los-difuntos-y-la-colada-morada-conserva-la-tradicion-del-ecuador\">\u00a0https:\/\/www.turismo.gob.ec\/dia-de-los-difuntos-y-la-colada-morada-conserva-la-tradicion-del-ecuador<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Hola a todos! Como en cada publicaci\u00f3n, hoy nuestra sopa de letras no pod\u00eda faltar. Esta vez, la tem\u00e1tica son &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-2176","post","type-post","status-publish","format-standard","hentry","category-uncategorized","latest_post"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9TuOs-z6","_links":{"self":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/2176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/comments?post=2176"}],"version-history":[{"count":2,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/2176\/revisions"}],"predecessor-version":[{"id":2198,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/2176\/revisions\/2198"}],"wp:attachment":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/media?parent=2176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/categories?post=2176"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/tags?post=2176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}