{"id":2004,"date":"2023-07-05T17:30:49","date_gmt":"2023-07-05T21:30:49","guid":{"rendered":"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/?p=2004"},"modified":"2023-07-06T17:11:25","modified_gmt":"2023-07-06T21:11:25","slug":"dia-18-4-de-julio-2023","status":"publish","type":"post","link":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/dia-18-4-de-julio-2023\/","title":{"rendered":"D\u00eda 18: 4 de julio, 2023"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Mercado internacional<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temprano en el d\u00eda hoy tuvimos un otro evento internacional&#8230;\u00a1un mercado entre la academia espa\u00f1ola, la academia francesa, y la academia alemana! Todos se sintieron emocionados y curiosos a ver lo que hicieron las otras academias. La academia espa\u00f1ola prepar\u00f3 cosas de arte como flores de papel, pulseras, y abanicos y comida como un postre de mangos y lima, sangr\u00eda sin alcohol, y una tabla de charcuter\u00eda. La mesa de pintura de caras era especialmente popular. Los franceses prepararon cosas de arte tambi\u00e9n, como banderas de pa\u00edses franc\u00f3fonos, abanicos, m\u00e1scaras, y gorros de papel. \u00a1Adem\u00e1s, prepararon cr\u00eapes,que fueron excelentes! Los alemanes prepararon joyer\u00eda como aretes y pulseras muy bonitas y a todos les gustaron. Despu\u00e9s de comprar y vender productos, empezamos los deportes.\u00a0<img decoding=\"async\" src=\"blob:https:\/\/www.vagovernorsschool.com\/2cd5c6df-974e-47bf-a6c7-cd5c8232febf\" alt=\"Inserting image...\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los juegos ol\u00edmpicos<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras algunas personas se quedaban en el mercado, despu\u00e9s de algun tiempo empezaron los juegos ol\u00edmpicos, otro evento internacional&nbsp; bajo el sol. Muchas gracias a todos los mentores por su trabajo duro porque ellos organizaron todos los juegos. Los participantes se dividieron en equipos diferentes con una mezcla de idiomas, y todos tuvieron que trabajar juntos durante los juegos como una carrera dentro de sacos de patatas y un curso de obst\u00e1culos (con una venda en los ojos). Al final el equipo azul gan\u00f3,&nbsp; pero todos disfrutaron mucho (y tomaron mucha agua despu\u00e9s).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fotos de ni\u00f1ez\/\u00bfqui\u00e9nes son?<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nosotros fuimos a un sal\u00f3n para una presentaci\u00f3n especial. Un poquito como sorpresa, la directora Guill\u00e9n nos present\u00f3 unas diapositivas con fotos de nosotros. Pero estas no fueron fotos normales: fueron fotos de cuando \u00e9ramos ni\u00f1os. Tuvimos que advinar qu\u00e9 estudiante era en cada diapositiva, y al final, revelaron nuestra identidad con unas fotos de c\u00f3mo aparecemos ahora. Era una actividad muy divertida con ambas caras diferentes y similares de la ni\u00f1ez y ahora.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bolas de fuego&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy le toc\u00f3 a la profe. Abarca ense\u00f1arnos algo de su pa\u00eds, El Salvador. Ella eligi\u00f3 el festival \u201cBolas de fuego\u201d para representar su pa\u00eds. Este festival se celebra cada 31 de agosto en Najapa con bolas de tela encendida. El prop\u00f3sito del d\u00eda <em>bolas de fuego<\/em> es para conmemorar la erupci\u00f3n en el pa\u00eds de El Salvador. Seg\u00fan la gente, en realidad fue una batalla contra San Jer\u00f3nimo y el diablo, y el acto de tirarse bolas de fuego simboliza lo que pas\u00f3 hace m\u00e1s de 100 a\u00f1os. Despu\u00e9s de su presentaci\u00f3n, la profe. Abarca nos mand\u00f3 al campo para simular <em>bolas de fuego<\/em> con globos de agua. Con la excepci\u00f3n de pocas personas, todos estuvieron mojados por el agua cuando ya se acabaron los globos que fueron preparados para la actividad. \u00a1Seguro que todos se divirtieron!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La noche de talentos internacional<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de dos d\u00edas de esperar, \u00a1tuvimos nuestra noche de talentos entre todas las academias! Los estudiantes de la academ\u00eda espa\u00f1ola que pudieron participar esta noche eran Sofia M, Amelia, Zoe, Austin, Owen, y Mannat. Sofia toc\u00f3 el ukelele y cant\u00f3 la canci\u00f3n \u201cDos Oruguitas\u201d, Amelia realiz\u00f3 un baile de ballet, Zoe toc\u00f3 la guitarra y cant\u00f3 una canci\u00f3n que ella tradujo del ingl\u00e9s al espa\u00f1ol, Austin y Owen realizaron un dueto muy gracioso en el piano, y Mannat bail\u00f3 un baile de su cultura de Punjabi. \u00a1Todos estamos muy orgullosos de nuestros estudiantes que representaron a nuestra academia! Los estudiantes de las otras academias tocaron instrumentos como la guitarra, ukelele, viol\u00edn, clarinete y m\u00e1s, y adem\u00e1s presentaron bailes de grupo y poes\u00eda. \u00a1Fue muy interesante mirar el talento y la \u00a0pasi\u00f3n de las otras academias!\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" src=\"blob:https:\/\/www.vagovernorsschool.com\/3e496738-6bc1-4286-8469-7b0b43a84d2b\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" src=\"blob:https:\/\/www.vagovernorsschool.com\/60137b45-8bc6-455b-84e8-2ebdde57f3bb\"><strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mercado internacional&nbsp; Temprano en el d\u00eda hoy tuvimos un otro evento internacional&#8230;\u00a1un mercado entre la academia espa\u00f1ola, la academia francesa, &hellip; <\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-2004","post","type-post","status-publish","format-standard","hentry","category-uncategorized","latest_post"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9TuOs-wk","_links":{"self":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/2004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/comments?post=2004"}],"version-history":[{"count":3,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/2004\/revisions"}],"predecessor-version":[{"id":2138,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/2004\/revisions\/2138"}],"wp:attachment":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/media?parent=2004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/categories?post=2004"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/tags?post=2004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}