{"id":1990,"date":"2023-07-02T17:18:29","date_gmt":"2023-07-02T21:18:29","guid":{"rendered":"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/?p=1990"},"modified":"2023-07-02T17:18:31","modified_gmt":"2023-07-02T21:18:31","slug":"dia-15-1-de-julio-2023","status":"publish","type":"post","link":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/dia-15-1-de-julio-2023\/","title":{"rendered":"D\u00eda 15: 1 de julio, 2023"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Actividad cultural con Marielis: sombreros de papel<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Hoy en la caja negra, la mentora Marielis nos ense\u00f1\u00f3 sobre la cultura cubana, en particular, los bailes. Nosotros aprendimos sobre las tradiciones importantes incluyendo crear un sombrero de papel. Siguiendo un v\u00eddeo muchos estudiantes hicieron estos sombreros mientras que otros bailaron. Sin duda, nos divertimos mucho con la m\u00fasica cubana de\u00a0fondo.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><img decoding=\"async\" src=\"blob:https:\/\/www.vagovernorsschool.com\/b4c5dadb-8902-4573-a6ac-740498937615\" alt=\"Inserting image...\"><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" src=\"blob:https:\/\/www.vagovernorsschool.com\/fc02b0c3-7d05-4ab1-bf76-b5a06782f256\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Preparando el baile internacional<\/strong>\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante nuestro tiempo de siesta, muchas personas estaban preparando el baile internacional. Algunas personas hicieron su pelo, usando alisadores y rizadores, y ayudando a amigos para hacerlo bien.&nbsp; Otras personas usaron el tiempo para hacer un desfile de moda, mostrando diferentes trajes a sus amigos, o debatiendo opciones por m\u00e1s tiempo que lo necesario. Y algunas personas tomaron la oportunidad para dormir, disfrutando la siesta mientras otros estaban estresados. Pero al fin, todos estuvieron casi listos.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Baile internacional<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Las academias de espa\u00f1ol, franc\u00e9s, y de alem\u00e1n se juntaron para el baile internacional!\u00a0Lo tuvimos en el gimnasio del campus, pero hab\u00eda una regla: no zapatos. Todos fueron al baile en ropa formal y calcetines para proteger el piso del gimnasio. Al llegar al gimnasio, todos bailamos juntos canciones espa\u00f1olas, alemanas, y francesas, jugamos con pelotas y globos, y conocimos y conversamos con personas nuevas de otras academias. \u00a1Fue una experiencia divertida y bonita, donde todos se juntaron para compartir su pasi\u00f3n para las lenguas de espa\u00f1ol, franc\u00e9s, y alem\u00e1n!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" src=\"blob:https:\/\/www.vagovernorsschool.com\/3fc6104f-ecb1-42f4-8daa-b180afd1c842\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" src=\"blob:https:\/\/www.vagovernorsschool.com\/251d0ea9-408c-404b-ab33-6a9188f3a32b\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actividad cultural con Marielis: sombreros de papel&nbsp; \u00a0Hoy en la caja negra, la mentora Marielis nos ense\u00f1\u00f3 sobre la cultura &hellip; <\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-1990","post","type-post","status-publish","format-standard","hentry","category-uncategorized","latest_post"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9TuOs-w6","_links":{"self":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/1990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/comments?post=1990"}],"version-history":[{"count":1,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/1990\/revisions"}],"predecessor-version":[{"id":1991,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/1990\/revisions\/1991"}],"wp:attachment":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/media?parent=1990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/categories?post=1990"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/tags?post=1990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}