{"id":1723,"date":"2022-06-30T17:18:58","date_gmt":"2022-06-30T21:18:58","guid":{"rendered":"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/?p=1723"},"modified":"2022-06-30T17:19:01","modified_gmt":"2022-06-30T21:19:01","slug":"las-alfombras","status":"publish","type":"post","link":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/las-alfombras\/","title":{"rendered":"Las alfombras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los participantes de La Academia Espa\u00f1ola empezaron el d\u00eda a las siete y cuarenta para desayunar. El veintiocho de Junio, fueron a las clases dos, tres, y cuatro. M\u00e1s tarde, la Profesora Abarca les ense\u00f1\u00f3 sobre Las Alfombras de Semana Santa, una tradici\u00f3n religiosa de varios pa\u00edses de Centroam\u00e9rica. Para practicar la celebraci\u00f3n, los estudiantes fueron afuera y dibujaron con tiza. Muchos dibujaron cualidades de la academia. De all\u00ed, se fueron a Stackhouse para ver el episodio diez de la telenovela <em>El tiempo entre costuras<\/em>. Siguiente el almuerzo, los estudiantes se reunieron en los grupos de tertulia escrita. Los estudiantes aprendieron sobre la gram\u00e1tica como el presente perfecto, el imperfecto, del subjuntivo, el pret\u00e9rito, etc. Tuvieron que hacer una escritura d\u00f3nde usaron la gram\u00e1tica que aprendieron y recibieron correcciones del profesor para consolidar ese aspecto de su gram\u00e1tica. Despu\u00e9s, regresaron a Stackhouse para ver presentaciones de tres grupos de proyectos. La tuna cant\u00f3 una canci\u00f3n y tocaron instrumentos, el grupo de baile present\u00f3 la bachata, y dise\u00f1o gr\u00e1fico present\u00f3 un video de fotos de eventos de la semana pasada. Despu\u00e9s de tener una hora de tiempo libre, todos se reunieron con los grupos de proyectos para empezar a prepararse para la tercera presentaci\u00f3n, mientras los grupos de la radio y de la telenovela todav\u00eda se preparaban para la segunda presentaci\u00f3n. Los estudiantes jugaron deportes afuera para terminar otro d\u00eda de la academia, antes de jugar Palabrle en la rotonda y recibir el correo de los padres.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2022\/06\/Alfombras.png\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" src=\"https:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2022\/06\/Alfombras-771x1024.png\" alt=\"\" class=\"wp-image-1725\" srcset=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2022\/06\/Alfombras-771x1024.png 771w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2022\/06\/Alfombras-226x300.png 226w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2022\/06\/Alfombras-768x1020.png 768w, http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-content\/uploads\/2022\/06\/Alfombras.png 792w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/a><figcaption>28\/06\/22<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Los participantes de La Academia Espa\u00f1ola empezaron el d\u00eda a las siete y cuarenta para desayunar. El veintiocho de Junio, &hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-1723","post","type-post","status-publish","format-standard","hentry","category-uncategorized","latest_post"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9TuOs-rN","_links":{"self":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/1723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/comments?post=1723"}],"version-history":[{"count":3,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/1723\/revisions"}],"predecessor-version":[{"id":1727,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/posts\/1723\/revisions\/1727"}],"wp:attachment":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/media?parent=1723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/categories?post=1723"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/tags?post=1723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}