{"id":318,"date":"2018-04-09T16:40:48","date_gmt":"2018-04-09T20:40:48","guid":{"rendered":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/?page_id=318"},"modified":"2021-05-03T09:45:05","modified_gmt":"2021-05-03T13:45:05","slug":"welcome","status":"publish","type":"page","link":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/welcome\/","title":{"rendered":"\u00a1Bienvenido!"},"content":{"rendered":"<p style=\"text-align: right;\"><span style=\"font-weight: 400;\">1 de mayo de 2021<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Estimado(a) estudiante:\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Me gustar\u00eda\u00a0 ser el primero en darte la bienvenida a la Academia Espa\u00f1ola del Gobernador 2021. Te felicito porque han sido tus habilidades, esfuerzo y empe\u00f1o los que te llevaron a ser aceptado(a) en tan selecto grupo. \u00a1Enhorabuena!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Este verano vas a formar parte de un selecto grupo de estudiantes que, durante tres semanas estara\u0301n inmersos en la lengua espan\u0303ola y la cultura hispa\u0301nica. <\/span><span style=\"font-weight: 400;\">Es un programa riguroso e intensivo que exige un alto nivel de participaci\u00f3n y energ\u00eda y cuyos frutos son inestimables. <\/span><span style=\"font-weight: 400;\">Una educacio\u0301n de estas caracteri\u0301sticas es una oportunidad u\u0301nica para sumergirte en los matices de una lengua tan rica y diversa como el espan\u0303ol. Sin duda, supondra\u0301 un reto para ti enfrentarte a una situacio\u0301n que requiere hablar, escuchar, leer y escribir en espan\u0303ol durante gran parte del di\u0301a. Pero estoy convencido de que saldra\u0301s exitoso\/a de esta prueba, y con mayor entusiasmo por el espan\u0303ol del que teni\u0301as antes de empezar la Academia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El estado actual de los acontecimientos en la nacio\u0301n y en el mundo entero nos ha llevado a tomar la decisio\u0301n de celebrar la Academia online de nuevo. Esta es una ocasio\u0301n excepcional, porque vivimos en tiempos excepcionales. No obstante, esto no va a impedir que tengas una experiencia educativa completa: tanto el profesorado como los mentores, y todos los implicados en la organizacio\u0301n de la Academia, hemos trabajado y seguiremos trabajando para que tu exposicio\u0301n al espan\u0303ol sea la ma\u0301xima posible.<\/span> <span style=\"font-weight: 400;\">Espero pues, que esta experiencia te valga como punto decisivo para la dedicaci\u00f3n de toda una vida al aprendizaje y al amor de la lengua espa\u00f1ola.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Revisa minuciosamente <\/span><span style=\"font-weight: 400;\">este documento. En e\u0301l encontrara\u0301s toda la informacio\u0301n necesaria acerca de los requisitos, expectativas y recomendaciones de la Academia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De parte del profesorado y de los mentores, te saludo muy afectuosamente con la esperanza de que esta academia sea para ti una experiencia inolvidable.\u00a0 Ya estoy anticipando conocerte a ti y a todo(a)s tus compa\u00f1ero(a)s el d\u00eda 21 de junio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quedo a la espera de tus prontas noticias,\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Brandon Norris<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Director<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La Academia Espa\u00f1ola del Gobernador 2021<\/span><\/p>\n<p><a href=\"mailto:VASpanishAcademy1@gmail.com\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-weight: 400;\">VASpanishAcademy1@gmail.com<\/span><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Para ma\u0301s informacio\u0301n, visita nuestra pa\u0301gina web :<\/span><\/p>\n<p><a href=\"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/\"><span style=\"font-weight: 400;\">http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/<\/span><\/a><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O puedes escribirme un correo electro\u0301nico a la direccio\u0301n arriba indicada.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1 de mayo de 2021 Estimado(a) estudiante:\u00a0\u00a0\u00a0\u00a0\u00a0 Me gustar\u00eda\u00a0 ser el primero en darte la bienvenida a la Academia Espa\u00f1ola &hellip; <\/p>\n","protected":false},"author":1,"featured_media":897,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-318","page","type-page","status-publish","has-post-thumbnail","hentry","latest_post"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/P9TuOs-58","_links":{"self":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/pages\/318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/comments?post=318"}],"version-history":[{"count":32,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/pages\/318\/revisions"}],"predecessor-version":[{"id":1507,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/pages\/318\/revisions\/1507"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/media\/897"}],"wp:attachment":[{"href":"http:\/\/www.vagovernorsschool.com\/SpanishAcademy\/wp-json\/wp\/v2\/media?parent=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}